{"id":8968,"date":"2026-05-24T10:06:52","date_gmt":"2026-05-24T09:06:52","guid":{"rendered":"https:\/\/fridaybulletin.co.uk\/experience-sensibilisation-religieuse-volume-03-numero-21\/"},"modified":"2026-05-24T11:29:01","modified_gmt":"2026-05-24T10:29:01","slug":"experience-sensibilisation-religieuse-volume-03-numero-21","status":"publish","type":"post","link":"https:\/\/fridaybulletin.co.uk\/fr\/experience-sensibilisation-religieuse-volume-03-numero-21\/","title":{"rendered":"Exp\u00e9rience sensibilisation religieuse \u2013 Volume 03 Num\u00e9ro 21"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1438.5px;margin-left: calc(-5% \/ 2 );margin-right: calc(-5% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.375%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:2.375%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:2.375%;--awb-spacing-left-medium:2.375%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:2.375%;--awb-spacing-left-small:2.375%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h2 style=\"text-align: center;\"><strong>Une subsistance inattendue en terre \u00e9trang\u00e8re<\/strong><\/h2>\n<p>C\u2019\u00e9tait au tout d\u00e9but de mon \u00e9migration en Europe, \u00e0 une \u00e9poque o\u00f9 la vie \u00e9tait douloureusement difficile et o\u00f9 la pression financi\u00e8re pesait lourdement sur chaque instant. Je vivais chez des proches et, malgr\u00e9 mes difficult\u00e9s, mon sens de la dignit\u00e9 m&rsquo;interdisait de demander de l&rsquo;argent \u00e0 quiconque. Je faisais tout mon possible pour trouver du travail. Pourtant, pour les amis que je voyais lors du rassemblement hebdomadaire de la pri\u00e8re de <em>Kumayl<\/em>, il \u00e9tait presque inimaginable qu&rsquo;un homme de religion puisse \u00eatre en proie \u00e0 de telles difficult\u00e9s. Ils supposaient que les personnes comme nous \u00e9taient toujours soutenues par des sources g\u00e9n\u00e9reuses et fiables.<\/p>\n<p>Un jour d&rsquo;automne, je me suis rendu au centre-ville pour d\u00e9poser mon CV \u00e0 diff\u00e9rents endroits. Les temps \u00e9taient si durs ce jour-l\u00e0 que je n&rsquo;avais pas un seul euro en poche. Au m\u00eame moment, un ami de ma ville natale m&rsquo;avait appel\u00e9, en d\u00e9tresse, et avait insist\u00e9 pour me voir le jour m\u00eame. \u00c0 l&rsquo;entendre, il s&rsquo;\u00e9tait retrouv\u00e9 face \u00e0 un probl\u00e8me qui ne pouvait pas attendre. Plus tard dans l&rsquo;apr\u00e8s-midi, apr\u00e8s avoir fini de distribuer mes CV et alors que je me dirigeais vers notre lieu de rendez-vous, quelque chose a attir\u00e9 mon attention. Un homme \u00e2g\u00e9 d\u00e9posait une partie de ses vieilles affaires sur le trottoir, devant son appartement, pour que les passants puissent prendre ce dont ils avaient besoin avant que le reste ne soit jet\u00e9. Parmi ces objets se trouvait une rang\u00e9e de livres, et ils m&rsquo;ont attir\u00e9 comme un aimant. Un petit tabouret se trouvait \u00e0 proximit\u00e9 ; je m&rsquo;y suis donc assis et j&rsquo;ai commenc\u00e9 \u00e0 les feuilleter. Voyant mon int\u00e9r\u00eat, le propri\u00e9taire a souri et a dit : \u00ab Ils sont tous \u00e0 vous. \u00bb Quelques instants plus tard, un passant s&rsquo;est arr\u00eat\u00e9 et, supposant que je vendais les livres, m&rsquo;a demand\u00e9 le prix d&rsquo;un magnifique roman en plusieurs volumes. Bien que je ne sois pas vraiment le vendeur, j&rsquo;ai r\u00e9pondu sous le coup de l&rsquo;impulsion : \u00ab Combien en donneriez-vous ? \u00bb Apr\u00e8s un bref \u00e9change et un peu de n\u00e9gociation, il m&rsquo;a tendu 80 euros pour l&rsquo;ensemble.<\/p>\n<p>Lorsque le propri\u00e9taire est redescendu avec d&rsquo;autres affaires, je lui ai racont\u00e9 ce qui s&rsquo;\u00e9tait pass\u00e9 et lui ai propos\u00e9 l&rsquo;argent. Mais il a ri chaleureusement et a dit : \u00ab Je vous ai donn\u00e9 ces livres, donc cet argent est \u00e0 vous aussi. \u00bb J&rsquo;ai insist\u00e9, mais il n&rsquo;a pas voulu le prendre. C&rsquo;est ainsi que, dot\u00e9 de ces 80 euros qui relevaient presque du miracle, je suis parti \u00e0 la rencontre de mon ami. Quand je l&rsquo;ai vu, son visage \u00e9tait tendu et tourment\u00e9. Il s&rsquo;est av\u00e9r\u00e9 que, juste pour s&rsquo;en sortir, il avait emprunt\u00e9 40 euros \u00e0 un autre \u00e9tudiant. Le moment \u00e9tait venu de les rembourser, mais il n&rsquo;avait rien, et la situation \u00e9tait devenue tendue entre eux. Sans h\u00e9sitation, j&rsquo;ai d\u00e9pos\u00e9 les 80 euros devant lui. \u00c0 ma surprise, il n&rsquo;a pris que les 40 euros dont il avait besoin et a refus\u00e9 le reste, malgr\u00e9 toute l&rsquo;insistance que je mettais \u00e0 vouloir qu&rsquo;il les garde.<\/p>\n<p>Cette journ\u00e9e m&rsquo;a donn\u00e9 une le\u00e7on durable : Dieu n&rsquo;abandonne pas le serviteur qui place sa confiance en Lui, et Il ne permet pas non plus qu&rsquo;une telle personne soit humili\u00e9e devant celle \u00e0 qui elle esp\u00e8re offrir son aide. Ma subsistance est venue d&rsquo;une rang\u00e9e de livres jet\u00e9s sur un trottoir, afin que je puisse devenir le moyen de pr\u00e9server la dignit\u00e9 d&rsquo;un fr\u00e8re croyant. Ce soir-l\u00e0, avec les 40 euros restants, j&rsquo;ai emmen\u00e9 ma femme et mon jeune enfant manger une glace. C&rsquo;\u00e9tait la glace la plus d\u00e9licieuse que j&rsquo;aie jamais go\u00fbt\u00e9e, car elle portait en elle la douceur de la confiance, de la gr\u00e2ce et de la b\u00e9n\u00e9diction.<\/p>\n<p><strong>Quelques le\u00e7ons tir\u00e9es de cette exp\u00e9rience<\/strong><\/p>\n<ul>\n<li><strong>Placer sa confiance en Dieu<\/strong> durant les moments difficiles apporte la paix et peut ouvrir des voies inattendues vers le soulagement et la facilit\u00e9 dans la vie.<\/li>\n<li><strong>Pr\u00e9server sa dignit\u00e9<\/strong> et son amour-propre, m\u00eame dans les moments difficiles, est une grande vertu humaine, surtout lorsqu&rsquo;elle s&rsquo;accompagne d&rsquo;efforts et d&rsquo;espoir.<\/li>\n<li><strong>La g\u00e9n\u00e9rosit\u00e9 et la gentillesse<\/strong>, comme en t\u00e9moigne le comportement du propri\u00e9taire de la maison, peuvent devenir une source de bienfaits et de b\u00e9n\u00e9dictions pour les autres.<\/li>\n<li><strong>\u00catre reconnaissant<\/strong> pour les petites b\u00e9n\u00e9dictions et savoir reconna\u00eetre la gr\u00e2ce dans les moments simples de la vie rend notre vision des choses plus profonde et plus douce.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":8940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[],"class_list":["post-8968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-experience-sensibilisation-religieuse"],"_links":{"self":[{"href":"https:\/\/fridaybulletin.co.uk\/fr\/wp-json\/wp\/v2\/posts\/8968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fridaybulletin.co.uk\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fridaybulletin.co.uk\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fridaybulletin.co.uk\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fridaybulletin.co.uk\/fr\/wp-json\/wp\/v2\/comments?post=8968"}],"version-history":[{"count":0,"href":"https:\/\/fridaybulletin.co.uk\/fr\/wp-json\/wp\/v2\/posts\/8968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fridaybulletin.co.uk\/fr\/wp-json\/wp\/v2\/media\/8940"}],"wp:attachment":[{"href":"https:\/\/fridaybulletin.co.uk\/fr\/wp-json\/wp\/v2\/media?parent=8968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fridaybulletin.co.uk\/fr\/wp-json\/wp\/v2\/categories?post=8968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fridaybulletin.co.uk\/fr\/wp-json\/wp\/v2\/tags?post=8968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}